{"id":3015,"date":"2023-01-12T11:22:29","date_gmt":"2023-01-12T03:22:29","guid":{"rendered":"https:\/\/www.penrote.com.tw\/wp-content\/uploads\/2021\/03\/KA5885-\u76f8\u7c3f.jpg"},"modified":"2023-01-12T11:22:29","modified_gmt":"2023-01-12T03:22:29","slug":"ka5885-%e7%9b%b8%e7%b0%bf","status":"inherit","type":"attachment","link":"https:\/\/www.penrote.com.tw\/en\/ka5885-%e7%9b%b8%e7%b0%bf\/","title":{"rendered":"KA5885-\u76f8\u7c3f"},"author":1,"featured_media":0,"comment_status":"","ping_status":"closed","template":"","meta":[],"media_folder":[79],"class_list":["post-3015","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.penrote.com.tw\/wp-content\/uploads\/2021\/03\/KA5885-\u76f8\u7c3f-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.penrote.com.tw\/wp-content\/uploads\/2021\/03\/KA5885-\u76f8\u7c3f-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.penrote.com.tw\/wp-content\/uploads\/2021\/03\/KA5885-\u76f8\u7c3f-300x300.jpg 300w, https:\/\/www.penrote.com.tw\/wp-content\/uploads\/2021\/03\/KA5885-\u76f8\u7c3f-1024x1024.jpg 1024w, https:\/\/www.penrote.com.tw\/wp-content\/uploads\/2021\/03\/KA5885-\u76f8\u7c3f-150x150.jpg 150w, https:\/\/www.penrote.com.tw\/wp-content\/uploads\/2021\/03\/KA5885-\u76f8\u7c3f-768x768.jpg 768w, https:\/\/www.penrote.com.tw\/wp-content\/uploads\/2021\/03\/KA5885-\u76f8\u7c3f-1536x1536.jpg 1536w, https:\/\/www.penrote.com.tw\/wp-content\/uploads\/2021\/03\/KA5885-\u76f8\u7c3f-2048x2048.jpg 2048w, https:\/\/www.penrote.com.tw\/wp-content\/uploads\/2021\/03\/KA5885-\u76f8\u7c3f-510x510.jpg 510w, https:\/\/www.penrote.com.tw\/wp-content\/uploads\/2021\/03\/KA5885-\u76f8\u7c3f-100x100.jpg 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":2560,"file":"2021\/03\/KA5885-\u76f8\u7c3f-scaled.jpg","filesize":186537,"sizes":{"medium":{"file":"KA5885-\u76f8\u7c3f-300x300.jpg","width":300,"height":300,"filesize":6441,"mime_type":"image\/jpeg","source_url":"https:\/\/www.penrote.com.tw\/wp-content\/uploads\/2021\/03\/KA5885-\u76f8\u7c3f-300x300.jpg"},"large":{"file":"KA5885-\u76f8\u7c3f-1024x1024.jpg","width":1024,"height":1024,"filesize":40184,"mime_type":"image\/jpeg","source_url":"https:\/\/www.penrote.com.tw\/wp-content\/uploads\/2021\/03\/KA5885-\u76f8\u7c3f-1024x1024.jpg"},"thumbnail":{"file":"KA5885-\u76f8\u7c3f-150x150.jpg","width":150,"height":150,"filesize":2709,"mime_type":"image\/jpeg","source_url":"https:\/\/www.penrote.com.tw\/wp-content\/uploads\/2021\/03\/KA5885-\u76f8\u7c3f-150x150.jpg"},"medium_large":{"file":"KA5885-\u76f8\u7c3f-768x768.jpg","width":768,"height":768,"filesize":25435,"mime_type":"image\/jpeg","source_url":"https:\/\/www.penrote.com.tw\/wp-content\/uploads\/2021\/03\/KA5885-\u76f8\u7c3f-768x768.jpg"},"1536x1536":{"file":"KA5885-\u76f8\u7c3f-1536x1536.jpg","width":1536,"height":1536,"filesize":78153,"mime_type":"image\/jpeg","source_url":"https:\/\/www.penrote.com.tw\/wp-content\/uploads\/2021\/03\/KA5885-\u76f8\u7c3f-1536x1536.jpg"},"2048x2048":{"file":"KA5885-\u76f8\u7c3f-2048x2048.jpg","width":2048,"height":2048,"filesize":126717,"mime_type":"image\/jpeg","source_url":"https:\/\/www.penrote.com.tw\/wp-content\/uploads\/2021\/03\/KA5885-\u76f8\u7c3f-2048x2048.jpg"},"woocommerce_thumbnail":{"file":"KA5885-\u76f8\u7c3f-247x296.jpg","width":247,"height":296,"filesize":6066,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/www.penrote.com.tw\/wp-content\/uploads\/2021\/03\/KA5885-\u76f8\u7c3f-247x296.jpg"},"woocommerce_single":{"file":"KA5885-\u76f8\u7c3f-510x510.jpg","width":510,"height":510,"filesize":13540,"mime_type":"image\/jpeg","source_url":"https:\/\/www.penrote.com.tw\/wp-content\/uploads\/2021\/03\/KA5885-\u76f8\u7c3f-510x510.jpg"},"woocommerce_gallery_thumbnail":{"file":"KA5885-\u76f8\u7c3f-100x100.jpg","width":100,"height":100,"filesize":1802,"mime_type":"image\/jpeg","source_url":"https:\/\/www.penrote.com.tw\/wp-content\/uploads\/2021\/03\/KA5885-\u76f8\u7c3f-100x100.jpg"},"shop_catalog":{"file":"KA5885-\u76f8\u7c3f-247x296.jpg","width":247,"height":296,"filesize":6066,"mime_type":"image\/jpeg","source_url":"https:\/\/www.penrote.com.tw\/wp-content\/uploads\/2021\/03\/KA5885-\u76f8\u7c3f-247x296.jpg"},"shop_single":{"file":"KA5885-\u76f8\u7c3f-510x510.jpg","width":510,"height":510,"filesize":13540,"mime_type":"image\/jpeg","source_url":"https:\/\/www.penrote.com.tw\/wp-content\/uploads\/2021\/03\/KA5885-\u76f8\u7c3f-510x510.jpg"},"shop_thumbnail":{"file":"KA5885-\u76f8\u7c3f-100x100.jpg","width":100,"height":100,"filesize":1802,"mime_type":"image\/jpeg","source_url":"https:\/\/www.penrote.com.tw\/wp-content\/uploads\/2021\/03\/KA5885-\u76f8\u7c3f-100x100.jpg"},"full":{"file":"KA5885-\u76f8\u7c3f-scaled.jpg","width":2560,"height":2560,"mime_type":"image\/jpeg","source_url":"https:\/\/www.penrote.com.tw\/wp-content\/uploads\/2021\/03\/KA5885-\u76f8\u7c3f-scaled.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"original_image":"KA5885-\u76f8\u7c3f.jpg"},"post":null,"source_url":"https:\/\/www.penrote.com.tw\/wp-content\/uploads\/2021\/03\/KA5885-\u76f8\u7c3f-scaled.jpg","_links":{"self":[{"href":"https:\/\/www.penrote.com.tw\/en\/wp-json\/wp\/v2\/media\/3015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.penrote.com.tw\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.penrote.com.tw\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.penrote.com.tw\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.penrote.com.tw\/en\/wp-json\/wp\/v2\/comments?post=3015"}],"wp:term":[{"taxonomy":"media_folder","embeddable":true,"href":"https:\/\/www.penrote.com.tw\/en\/wp-json\/wp\/v2\/media_folder?post=3015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}